{"id":713,"date":"2020-03-16T10:19:57","date_gmt":"2020-03-16T18:19:57","guid":{"rendered":"http:\/\/71.243.216.88\/personal-de-esfrn\/"},"modified":"2025-06-18T14:07:53","modified_gmt":"2025-06-18T22:07:53","slug":"personal-de-esfrn","status":"publish","type":"page","link":"https:\/\/www.esfrn.org\/es\/personal-de-esfrn\/","title":{"rendered":"Personal de FRN"},"content":{"rendered":"<h2>\n<p>Conocer al Equipo<\/h2>\n<div class=\"row\">\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/Janice-Hinton300x300.png\" alt=\"Janice Hinton\" class=\"profile-img\"><\/p>\n<h2>Janice Hinton<\/h2>\n<p class=\"title\">Gerente<\/p>\n<p>jhinton@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/Alycia-Licon300x300.png\" alt=\"Alycia Licon\" class=\"profile-img\"><\/p>\n<h2>Alycia Licon<\/h2>\n<p class=\"title\">Coordinadora de Programa<\/p>\n<p>alicon@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>   <\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/06\/Rose-Juarez300x300.png\" alt=\"Rose Juarez\" class=\"profile-img\"><\/p>\n<h2>Rose Juarez<\/h2>\n<p class=\"title\">Secretaria<\/p>\n<p>rjuarez@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/Leahnna-Olmedo300x300.png\" alt=\"Leahnna Olmedo\" class=\"profile-img\"><\/p>\n<h2>Leahnna Olmedo<\/h2>\n<p class=\"title\">Coordinador de Datos y Alcance<\/p>\n<p>lolmedo@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/Stephanie-Inclan300x300.png\" alt=\"Stephanie Inclan\" class=\"profile-img\"><\/p>\n<h2>Stephanie Inclan<\/h2>\n<p class=\"title\">Asistente de Datos y Alcance<\/p>\n<p>sinclan@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/06\/Noushin-Azimzadgan300x300.png\" alt=\"Noushin Azimzadgan\" class=\"profile-img\"><\/p>\n<h2>Noushin <span style=\"font-size: 0.9em; letter-spacing: -0.5px;\">Azimzadgan<\/span><\/h2>\n<p class=\"title\">Representante de Padres<\/p>\n<p>nazimzadgan@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/Mariza-Hernandez300x300.png\" alt=\"Mariza Hernandez\" class=\"profile-img\"><\/p>\n<h2>Mariza Hernandez<\/h2>\n<p class=\"title\">Representante de Padres<\/p>\n<p>mhernandez@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p> <\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/Blanca-Loria300x300.png\" alt=\"Blanca Loria\" class=\"profile-img\"><\/p>\n<h2>Blanca Loria<\/h2>\n<p class=\"title\">Representante de Padres<\/p>\n<p>bloria@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/TeiYana-Muse300x300.png\" alt=\"TeiYana Muse\" class=\"profile-img\"><\/p>\n<h2>TeiYana Muse<\/h2>\n<p class=\"title\">Representante de Padres<\/p>\n<p>tmuse@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/06\/Maira-Gutierrez300x300.png\" alt=\"Maira Gutierrez\" class=\"profile-img\"><\/p>\n<h2>Maira Gutierrez<\/h2>\n<p class=\"title\">Especialista en Apoyo Familiar<\/p>\n<p>maigutierrez@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/06\/Adriana-Moreno300x300.png\" alt=\"Adriana Moreno\" class=\"profile-img\"><\/p>\n<h2>Adriana Moreno<\/h2>\n<p class=\"title\">Especialista en Apoyo Familiar<\/p>\n<p>amoreno@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p> <\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n<h2><\/h2>\n<p class=\"title\">\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/Angela-Taber300x300.png\" alt=\"Angela Taber\" class=\"profile-img\"><\/p>\n<h2>Angela Taber<\/h2>\n<p class=\"title\">Especialista en Apoyo Familiar<\/p>\n<p>ataber@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p> <\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/06\/Walter-Tejada300x300.png\" alt=\"Walter Tejada\" class=\"profile-img\"><\/p>\n<h2>Walter Tejada<\/h2>\n<p class=\"title\">Especialista en Apoyo Familiar<\/p>\n<p>wtejada@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p> <\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n<h2><\/h2>\n<p class=\"title\">\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/Audrey-Fausett300x300.png\" alt=\"Audrey Fausett\" class=\"profile-img\"><\/p>\n<h2>Audrey Fausett<\/h2>\n<p class=\"title\">Navegador de la Comunidad<\/p>\n<p>afausett@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><\/p>\n<div class=\"column\">\n<div class=\"card\">\n<div class=\"container\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/12\/Sandy-Solis300x300.png\" alt=\"Sandy Solis\" class=\"profile-img\"><\/p>\n<h2>Sandy Solis<\/h2>\n<p class=\"title\">Navegador de la Comunidad<\/p>\n<p>ssolis@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p> <\/p>\n<div class=\"column\">\n<div class=\"card\">\n     <img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/06\/Vicky-Murillo300x300.png\" alt=\"Vicky Murillo\" class=\"profile-img\"><\/p>\n<div class=\"container\">\n<h2>Vicky Murillo<\/h2>\n<p class=\"title\">Navegador de la Comunidad<\/p>\n<p>vmurillo@inlandrc.org<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Conocer al Equipo Janice Hinton Gerente jhinton@inlandrc.org Alycia Licon Coordinadora de Programa alicon@inlandrc.org Rose Juarez Secretaria rjuarez@inlandrc.org Leahnna Olmedo Coordinador de Datos y Alcance lolmedo@inlandrc.org&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.esfrn.org\/es\/personal-de-esfrn\/\">Lee mas<span class=\"screen-reader-text\">Personal de FRN<\/span><\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_lmt_disableupdate":"no","_lmt_disable":"","footnotes":""},"class_list":["post-713","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/www.esfrn.org\/es\/wp-json\/wp\/v2\/pages\/713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esfrn.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.esfrn.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.esfrn.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esfrn.org\/es\/wp-json\/wp\/v2\/comments?post=713"}],"version-history":[{"count":20,"href":"https:\/\/www.esfrn.org\/es\/wp-json\/wp\/v2\/pages\/713\/revisions"}],"predecessor-version":[{"id":6338,"href":"https:\/\/www.esfrn.org\/es\/wp-json\/wp\/v2\/pages\/713\/revisions\/6338"}],"wp:attachment":[{"href":"https:\/\/www.esfrn.org\/es\/wp-json\/wp\/v2\/media?parent=713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}